{"id":26853,"date":"2026-03-20T05:53:55","date_gmt":"2026-03-20T05:53:55","guid":{"rendered":"https:\/\/suizhoutruck.com\/?post_type=vehica_car&#038;p=26853"},"modified":"2026-03-26T02:59:31","modified_gmt":"2026-03-26T02:59:31","slug":"camion-de-succion-de-aguas-residuales-dongfeng-d9","status":"publish","type":"vehica_car","link":"https:\/\/suizhoutruck.com\/es\/product\/dongfeng-d9-sewage-suction-truck\/","title":{"rendered":"Cami\u00f3n aspirador de aguas residuales Dongfeng D9"},"content":{"rendered":"<p>Parte superior:<br \/>\nCuerpo del tanque: El cuerpo del tanque tiene un volumen aproximado de 13,5 metros c\u00fabicos y est\u00e1 construido con placas de acero al carbono de alta calidad de 6 mm de espesor;<br \/>\nSecci\u00f3n de succi\u00f3n de aguas residuales: La bomba de succi\u00f3n de aguas residuales adopta una bomba de vac\u00edo de circulaci\u00f3n de agua SK-15 o una bomba de vac\u00edo de circulaci\u00f3n de aceite de 10 toneladas. La parte superior del tanque de aguas residuales est\u00e1 equipada con una v\u00e1lvula antidesbordamiento con una rejilla de filtro, (bomba de vac\u00edo y tanque de agua peque\u00f1o con una v\u00e1lvula de drenaje), v\u00e1lvula de cuatro v\u00edas Black Diamond, tubo de medici\u00f3n de nivel de l\u00edquido y v\u00e1lvula multidireccional;<br \/>\nOtros requisitos de configuraci\u00f3n: plataforma para la instalaci\u00f3n de tuber\u00edas a ambos lados con placas estampadas, barandillas de acero inoxidable, sistema hidr\u00e1ulico de elevaci\u00f3n y descarga del tanque, mecanismo hidr\u00e1ulico de apertura y cierre de la tapa trasera con cuatro dispositivos de bloqueo; puerto de succi\u00f3n de aguas residuales de 100 mm en el lado derecho del tanque y puerto de descarga de aguas residuales de 150 mm en la parte trasera. Tuber\u00eda de succi\u00f3n de aguas residuales de 100 mm y 8 metros de longitud, y color general del veh\u00edculo: amarillo ingenier\u00eda.<br \/>\nVentajas: 1. El veh\u00edculo completo est\u00e1 fabricado con componentes cortados con l\u00e1ser; 2. La soldadura independiente se realiza antes de la pintura; 3. Producci\u00f3n estandarizada (atmosf\u00e9rica y est\u00e9ticamente agradable), con mayor estabilidad y durabilidad.<\/p>","protected":false},"author":78,"featured_media":0,"template":"","vehica_23670":[2501],"vehica_6655":[2505],"vehica_6660":[],"vehica_6661":[2573],"vehica_6663":[2108],"vehica_24340":[2527],"vehica_24341":[],"vehica_12974":[],"vehica_24362":[],"vehica_6670":[],"vehica_24789":[],"class_list":["post-26853","vehica_car","type-vehica_car","status-publish","hentry","vehica_23670-used","vehica_6655-garbage-truck","vehica_6661-4x2drive","vehica_6663-diesel","vehica_24340-dongfeng"],"vehica_24797":"4500MM","vehica_24798":"","vehica_24922":"","vehica_24799":"195\/230horsepower","vehica_14696":"","vehica_6665":"","vehica_24349":["https:\/\/suizhoutruck.com\/wp-content\/uploads\/2026\/03\/\u56fe\u72471-14-scaled.png","https:\/\/suizhoutruck.com\/wp-content\/uploads\/2026\/03\/\u56fe\u72472-14.png","https:\/\/suizhoutruck.com\/wp-content\/uploads\/2026\/03\/\u56fe\u72473-14.png","https:\/\/suizhoutruck.com\/wp-content\/uploads\/2026\/03\/\u56fe\u72474-14.png","https:\/\/suizhoutruck.com\/wp-content\/uploads\/2026\/03\/\u56fe\u72475-12.png","https:\/\/suizhoutruck.com\/wp-content\/uploads\/2026\/03\/\u56fe\u72476-12.png","https:\/\/suizhoutruck.com\/wp-content\/uploads\/2026\/03\/\u56fe\u72477-11.png"],"vehica_6674":{"url":"","embed":""},"vehica_16721":"","vehica_18820":[],"_links":{"self":[{"href":"https:\/\/suizhoutruck.com\/es\/wp-json\/wp\/v2\/cars\/26853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suizhoutruck.com\/es\/wp-json\/wp\/v2\/cars"}],"about":[{"href":"https:\/\/suizhoutruck.com\/es\/wp-json\/wp\/v2\/types\/vehica_car"}],"author":[{"embeddable":true,"href":"https:\/\/suizhoutruck.com\/es\/wp-json\/wp\/v2\/users\/78"}],"wp:attachment":[{"href":"https:\/\/suizhoutruck.com\/es\/wp-json\/wp\/v2\/media?parent=26853"}],"wp:term":[{"taxonomy":"vehica_23670","embeddable":true,"href":"https:\/\/suizhoutruck.com\/es\/wp-json\/wp\/v2\/vehica_23670?post=26853"},{"taxonomy":"vehica_6655","embeddable":true,"href":"https:\/\/suizhoutruck.com\/es\/wp-json\/wp\/v2\/vehica_6655?post=26853"},{"taxonomy":"vehica_6660","embeddable":true,"href":"https:\/\/suizhoutruck.com\/es\/wp-json\/wp\/v2\/vehica_6660?post=26853"},{"taxonomy":"vehica_6661","embeddable":true,"href":"https:\/\/suizhoutruck.com\/es\/wp-json\/wp\/v2\/vehica_6661?post=26853"},{"taxonomy":"vehica_6663","embeddable":true,"href":"https:\/\/suizhoutruck.com\/es\/wp-json\/wp\/v2\/vehica_6663?post=26853"},{"taxonomy":"vehica_24340","embeddable":true,"href":"https:\/\/suizhoutruck.com\/es\/wp-json\/wp\/v2\/vehica_24340?post=26853"},{"taxonomy":"vehica_24341","embeddable":true,"href":"https:\/\/suizhoutruck.com\/es\/wp-json\/wp\/v2\/vehica_24341?post=26853"},{"taxonomy":"vehica_12974","embeddable":true,"href":"https:\/\/suizhoutruck.com\/es\/wp-json\/wp\/v2\/vehica_12974?post=26853"},{"taxonomy":"vehica_24362","embeddable":true,"href":"https:\/\/suizhoutruck.com\/es\/wp-json\/wp\/v2\/vehica_24362?post=26853"},{"taxonomy":"vehica_6670","embeddable":true,"href":"https:\/\/suizhoutruck.com\/es\/wp-json\/wp\/v2\/vehica_6670?post=26853"},{"taxonomy":"vehica_24789","embeddable":true,"href":"https:\/\/suizhoutruck.com\/es\/wp-json\/wp\/v2\/vehica_24789?post=26853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}